{"id":6941,"date":"2024-03-05T12:13:55","date_gmt":"2024-03-05T17:13:55","guid":{"rendered":"https:\/\/futurpreneur.ca\/resource\/liste-pour-mentor-et-je-nouveaux-arrivants\/"},"modified":"2024-04-09T16:10:55","modified_gmt":"2024-04-09T20:10:55","slug":"liste-pour-mentor-et-je-nouveaux-arrivants","status":"publish","type":"resource","link":"https:\/\/futurpreneur.ca\/fr\/resource\/liste-pour-mentor-et-je-nouveaux-arrivants\/","title":{"rendered":"Liste pour mentor et JE nouveaux arrivants"},"content":{"rendered":"\n<p>Pour ne rien oublier lors des rencontres mentorat entre un nouvel arrivant et son mentor.<\/p>\n\n\n\n<p>Dans le cadre du Programme d\u2019entrepreneuriat Futurpreneur pour les nouveaux arrivants, Futurpreneur&nbsp; a proc\u00e9d\u00e9 \u00e0 votre jumelage avec un mentor b\u00e9n\u00e9vole, issu du monde des affaires, qui vous offrira un encadrement pr\u00e9cieux et du soutien pour vous aider \u00e0 mettre sur pied votre entreprise.<\/p>\n\n\n\n<p>Au cours des deux prochaines ann\u00e9es, votre mentor de Futurpreneur vous posera des questions, vous donnera des exemples personnels et des suggestions mais vous, comme propri\u00e9taire, aurez la responsabilit\u00e9 de prendre toutes les d\u00e9cisions concernant votre nouvelle entreprise.<\/p>\n\n\n\n<p>Maintenant que vous commencez \u00e0 travailler avec un mentor, vous vous demandez peut-\u00eatre comment tirer le plus grand profit de vos conversations avec lui. En plus des sujets propos\u00e9s par l\u2019atelier en ligne Entre NousMD, nous avons dress\u00e9 une liste de v\u00e9rification pour la relation de mentorat qui comporte des \u00e9l\u00e9ments d\u2019une pertinence particuli\u00e8re pour les entrepreneurs nouvellement arriv\u00e9s au pays.<\/p>\n\n\n\n<p>Voici comment faire le meilleur usage de cette liste de v\u00e9rification :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Passez en revue cette liste de sujets avec votre mentor et d\u00e9terminez ceux qui vous semblent prioritaires et qui devraient faire l\u2019objet d\u2019une discussion au cours des premi\u00e8res rencontres.<\/li>\n\n\n\n<li>Ajoutez toute question dont vous aimeriez parler avec votre mentor.<\/li>\n\n\n\n<li>Rappelez-vous que le Guide de Futurpreneur \u00e0 l\u2019intention des nouveaux arrivants entrepreneurs est rempli de renseignements utiles et de liens vers des sites Web qui vous offrent plus de d\u00e9tails sur certains sujets; consid\u00e9rez votre mentor comme celui qui peut vous fournir une meilleure connaissance de tous les aspects li\u00e9s \u00e0 votre milieu de vie \u00e0 l\u2019\u00e9chelle locale et des opinions fond\u00e9es sur sa propre exp\u00e9rience.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Priorit\u00e9<\/th><th>Termin\u00e9<\/th><th>Sujets de discussion \u00e0 aborder durant les rencontres de mentorat<\/th><\/tr><\/thead><tbody><tr><td><\/td><td><\/td><td><strong>Plan d\u2019affaires<\/strong><p><\/p>\n<p>Pour obtenir un pr\u00eat, il vous faut un plan d\u2019affaires. C\u2019est \u00e9galement essentiel pour mettre votre entreprise sur pied et vous orienter dans la bonne voie. Vous souhaiterez peut-\u00eatre discuter avec votre mentor des \u00e9l\u00e9ments qui constituent un plan d\u2019affaires, de la mani\u00e8re de le commencer et de le mettre \u00e0 jour.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Financement<\/strong><p><\/p>\n<p>La plupart des entreprises ont besoin de financement provenant de sources ext\u00e9rieures. Votre mentor peut vous aider \u00e0 \u00e9valuer les diff\u00e9rentes options qui vous sont offertes.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Structure d\u2019entreprise<\/strong><p><\/p>\n<p>Le type de structure d\u2019entreprise que vous choisissez d\u00e9terminera les frais de pr\u00e9ouverture et les taxes que vous devrez payer, de m\u00eame que les rapports financiers, les op\u00e9rations et les obligations juridiques \u00e0 assumer.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Droit du travail<\/strong><p><\/p>\n<p>Au Canada, des lois et des r\u00e9glementations provinciales et nationales prot\u00e8gent les droits des travailleurs. Les propri\u00e9taires d\u2019entreprises qui comptent des employ\u00e9s doivent comprendre les normes qui r\u00e9gissent des \u00e9l\u00e9ments tels que le salaire minimum, les horaires de travail et la sant\u00e9 et s\u00e9curit\u00e9 en milieu de travail.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Op\u00e9rations bancaires<\/strong><p><\/p>\n<p>Chaque pays a des approches diff\u00e9rentes en ce qui a trait aux op\u00e9rations bancaires. Les banques canadiennes proposent de nombreuses options aux propri\u00e9taires d\u2019entreprises. Vous comprendrez mieux le choix qui vous est offert apr\u00e8s en avoir discut\u00e9 avec votre mentor.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Taxes<\/strong><p><\/p>\n<p>En vertu des lois, les propri\u00e9taires d\u2019entreprises doivent percevoir et remettre les taxes de vente et payer des retenues \u00e0 la source, des taxes municipales et des imp\u00f4ts sur le revenu. Pour \u00e9viter les difficult\u00e9s financi\u00e8res et juridiques, vous devez comprendre vos obligations en mati\u00e8re de taxes.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Cycles \u00e9conomiques<\/strong><p><\/p>\n<p>Comprendre la nature des cycles \u00e9conomiques \u2013 ou conjoncturels \u2013 peut permettre \u00e0 l\u2019entrepreneur de pr\u00e9voir les diff\u00e9rents comportements des secteurs d\u2019industries, des banques, des clients et des fournisseurs.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Terminologie des affaires<\/strong><p><\/p>\n<p>Tout propri\u00e9taire d\u2019entreprise doit apprendre les mots et les phrases courantes en affaires et comment s\u2019en servir au sein de sa propre entreprise. Invitez votre mentor \u00e0 discuter de ces termes avec vous et \u00e0 vous faire partager ses connaissances et ses exp\u00e9riences.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Comp\u00e9tences en communications<\/strong><p><\/p>\n<p>Les entrepreneurs qui ont de solides connaissances en communications obtiennent beaucoup de succ\u00e8s dans leurs relations avec la client\u00e8le, les fournisseurs et leurs contacts d\u2019affaires. Discutez de votre style de communication verbale et \u00e9crite avec votre mentor et demandez-lui de vous donner des suggestions pour am\u00e9liorer et renforcer vos comp\u00e9tences en communications.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Communication \u00e9lectronique<\/strong> <p>Pour \u00e9tablir des relations, la plupart des entrepreneurs communiquent par voie \u00e9lectronique, \u00e0 l\u2019aide d\u2019outils tels que la messagerie vocale, le courrier \u00e9lectronique ou la messagerie texte. Parlez avec votre mentor des pratiques courantes, des attentes et de l\u2019\u00e9tiquette professionnelle<br>qui s\u2019applique \u00e0 ces moyens de communication.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>R\u00e9seautage<\/strong><p><\/p>\n<p>Demandez \u00e0 votre mentor comment la planification et le d\u00e9veloppement de votre r\u00e9seau peut vous aider \u00e0 b\u00e2tir votre entreprise et quelles strat\u00e9gies peuvent vous permettre de vous rapprocher de la communaut\u00e9 d\u2019affaires, de vos associ\u00e9s et coll\u00e8gues. Votre mentor a peut-\u00eatre des id\u00e9es sur les meilleures approches de r\u00e9seautage \u00e0 adopter et les \u00e9v\u00e9nements auxquels vous pourriez participer. \u00c9tiquette sociale et professionnelle<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>\u00c9tiquette sociale et professionnelle<\/strong> <p>Il est tr\u00e8s probable que certaines coutumes de votre pays d\u2019origine diff\u00e8rent de celles du Canada. Il pourrait \u00eatre utile que vous abordiez les \u00e9l\u00e9ments qui suivent avec votre mentor :<\/p><ul><li>l\u2019utilisation des titres de civilit\u00e9 (M. \/ Mme);<\/li><li>la poign\u00e9e de main et le contact visuel;<\/li><li>les bonnes mani\u00e8res \u00e0 table;<\/li><li>la n\u00e9gociation;<\/li><li>la tenue vestimentaire en milieu de travail;<\/li><li>les cadeaux.<\/li><\/ul><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Les attentes en mati\u00e8re de service<\/strong><p><\/p>\n<p>Le succ\u00e8s de votre entreprise est tributaire de votre capacit\u00e9 \u00e0 offrir un niveau de service acceptable \u00e0 vos clients et fournisseurs. Vous devez comprendre leurs attentes, notamment en ce qui \u00e0 trait aux d\u00e9lais de r\u00e9ponse et de paiement, ainsi qu\u2019aux plaintes sur la qualit\u00e9 et la manutention.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>\u00c9tablissement de prix<\/strong> <p>Que vous vendiez ou achetiez des fournitures, il vous faut comprendre les pratiques canadiennes en mati\u00e8re d\u2019\u00e9tablissement de prix. Dans quelles circonstances devez-vous payer plus que le montant demand\u00e9 en donnant un pourboire? \u00c0 quel moment et comment devriez-vous n\u00e9gocier un prix plus bas pour vos achats?<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Propri\u00e9t\u00e9 intellectuelle<\/strong><p><\/p>\n<p>Les propri\u00e9taires d\u2019entreprises doivent savoir quand et comment prot\u00e9ger leurs id\u00e9es cr\u00e9atives et \u00e9viter la violation de la propri\u00e9t\u00e9 intellectuelle des autres, ce qui pourrait entra\u00eener de s\u00e9rieuses p\u00e9nalit\u00e9s.<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>\u00c9tablissement de prix<\/strong> <p>Que vous vendiez ou achetiez des fournitures, il vous faut comprendre les pratiques canadiennes en mati\u00e8re d\u2019\u00e9tablissement de prix. Dans quelles circonstances devez-vous payer plus que le montant demand\u00e9 en donnant un pourboire? \u00c0 quel moment et comment devriez-vous n\u00e9gocier un prix plus bas pour vos achats?<\/p><\/td><\/tr><tr><td><\/td><td><\/td><td><strong>Responsabilit\u00e9 sociale<\/strong> <p>La plupart des entreprises canadiennes ont pris un engagement en mati\u00e8re de responsabilit\u00e9 sociale. Par exemple, il peut s\u2019agir d\u2019appuyer des initiatives communautaires locales en offrant du temps ou des dons, en r\u00e9duisant l\u2019impact environnemental de l\u2019entreprise ou m\u00eame en faisant des affaires dans des secteurs \u00e0 faible revenu mal desservis.<\/p><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Pour ne rien oublier lors des rencontres mentorat entre un nouvel arrivant et son mentor. Dans le cadre du Programme d\u2019entrepreneuriat Futurpreneur pour les nouveaux arrivants, Futurpreneur&nbsp; a proc\u00e9d\u00e9 \u00e0 votre jumelage avec un mentor b\u00e9n\u00e9vole, issu du monde des affaires, qui vous offrira un encadrement pr\u00e9cieux et du soutien pour vous aider \u00e0 mettre [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","resource_category":[65],"resource_type":[98],"resource_phase":[108,109,110],"class_list":["post-6941","resource","type-resource","status-publish","hentry","resource_category-mentorat","resource_type-cours","resource_phase-mentorat-grandir","resource_phase-mentorat-preparer","resource_phase-mentorat-soutenir"],"acf":[],"_links":{"self":[{"href":"https:\/\/futurpreneur.ca\/fr\/wp-json\/wp\/v2\/resource\/6941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futurpreneur.ca\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/futurpreneur.ca\/fr\/wp-json\/wp\/v2\/types\/resource"}],"version-history":[{"count":0,"href":"https:\/\/futurpreneur.ca\/fr\/wp-json\/wp\/v2\/resource\/6941\/revisions"}],"wp:attachment":[{"href":"https:\/\/futurpreneur.ca\/fr\/wp-json\/wp\/v2\/media?parent=6941"}],"wp:term":[{"taxonomy":"resource_category","embeddable":true,"href":"https:\/\/futurpreneur.ca\/fr\/wp-json\/wp\/v2\/resource_category?post=6941"},{"taxonomy":"resource_type","embeddable":true,"href":"https:\/\/futurpreneur.ca\/fr\/wp-json\/wp\/v2\/resource_type?post=6941"},{"taxonomy":"resource_phase","embeddable":true,"href":"https:\/\/futurpreneur.ca\/fr\/wp-json\/wp\/v2\/resource_phase?post=6941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}